{"id":1983,"count":2,"description":"","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/ociomodell-pinturas\/pinturas-oleo\/","name":"Pintura - Oleo","slug":"pinturas-oleo","taxonomy":"category","parent":27,"meta":[],"_links":{"self":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/categories\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/categories\/27"}],"wp:post_type":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts?categories=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}