{"id":8141,"date":"2023-08-23T19:22:55","date_gmt":"2023-08-23T18:22:55","guid":{"rendered":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/"},"modified":"2023-08-30T17:25:37","modified_gmt":"2023-08-30T16:25:37","slug":"clients","status":"publish","type":"page","link":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/","title":{"rendered":"Tem\u00e1ticos"},"content":{"rendered":"<figure id=\"attachment_8284\" aria-describedby=\"caption-attachment-8284\" style=\"width: 261px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/wp.me\/P7mZwQ-28i\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8284\" data-permalink=\"https:\/\/blog.ociomodell.com\/wordpress\/clients\/demostraciones-de-paso-a-paso-de-realizacion-de-diversas-tecnicas\/llmbuls0nns66iwbigczmo0pnvpcfsm6ykfovzpz3ygxjdsynm1\/\" data-orig-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1.png\" data-orig-size=\"915,1050\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Vallejo\" data-image-description=\"&lt;p&gt;Vallejo&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Vallejo&lt;\/p&gt;\n\" data-large-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-892x1024.png\" class=\"size-medium wp-image-8284\" src=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-261x300.png\" alt=\"Vallejo\" width=\"261\" height=\"300\" title=\"\" srcset=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-261x300.png 261w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-892x1024.png 892w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-768x881.png 768w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1-250x287.png 250w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/lLMbULS0nns66IwBIgcZMO0pnVPCfSm6yKFOvzPZ3ygxjdSYnM1.png 915w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/a><figcaption id=\"caption-attachment-8284\" class=\"wp-caption-text\">Vallejo<\/figcaption><\/figure>\n<p><a href=\"https:\/\/wp.me\/P7mZwQ-28i\" target=\"_blank\" rel=\"noopener nofollow\">VALLEJO<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VALLEJO<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-8141","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8205,"url":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/demostraciones-de-paso-a-paso-de-realizacion-de-diversas-tecnicas\/efectos-agua-profunda\/","url_meta":{"origin":8141,"position":0},"title":"Efectos agua profunda &#8211; Vallejo","author":"Paco Gomez","date":"26 agosto, 2023","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"Vallejo - Efectos agua profunda","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/vallejo-pasoapaso-efectos-de-agua-profunda-usando-texturas-de-agua-Vallejo-ES.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8211,"url":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/demostraciones-de-paso-a-paso-de-realizacion-de-diversas-tecnicas\/efecto-luminoso-de-gemma\/","url_meta":{"origin":8141,"position":1},"title":"Efecto luminoso de gemma &#8211; Vallejo","author":"Paco Gomez","date":"26 agosto, 2023","format":false,"excerpt":"","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"Vallejo - Efecto Gemma","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/vallejo-pasoapaso-como-pintar-efecto-luminoso-de-gema-ES.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8225,"url":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/demostraciones-de-paso-a-paso-de-realizacion-de-diversas-tecnicas\/masilla-plastica-y-lijado\/","url_meta":{"origin":8141,"position":2},"title":"Masilla pl\u00e1stica y lijado &#8211; Vallejo","author":"Paco Gomez","date":"26 agosto, 2023","format":false,"excerpt":"En este tutorial se expone el uso de la Masilla Pl\u00e1stica y su posterior proceso de lijado, para corregir posibles defectos de encaje sobre un modelo o figura.","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"Vallejo - Masilla pl\u00e1stica","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/vallejo-pasoapaso-como-usar-masilla-plastica-ES.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3497,"url":"https:\/\/blog.ociomodell.com\/wordpress\/catalogos\/catalogos-2018\/","url_meta":{"origin":8141,"position":3},"title":"Cat\u00e1logos 2018","author":"Paco Gomez","date":"17 junio, 2018","format":false,"excerpt":"Ir a Cat\u00e1logos \u00a0 \u00a0 \u00a0 \u00a0","rel":"","context":"En \u00ab2018\u00bb","block_context":{"text":"2018","link":"https:\/\/blog.ociomodell.com\/wordpress\/tag\/2018\/"},"img":{"alt_text":"AMMO - Cat\u00e1logo 2018 de Ammo","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/01\/AMMO-catalogue_2018_redu-211x300.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3535,"url":"https:\/\/blog.ociomodell.com\/wordpress\/catalogos\/catalogos-2017\/","url_meta":{"origin":8141,"position":4},"title":"Cat\u00e1logos 2017","author":"Paco Gomez","date":"17 junio, 2018","format":false,"excerpt":"Ir a cat\u00e1logos del 2018 \u00a0 \u00a0 \u00a0","rel":"","context":"En \u00ab2017\u00bb","block_context":{"text":"2017","link":"https:\/\/blog.ociomodell.com\/wordpress\/tag\/2017\/"},"img":{"alt_text":"Disarmodel - Cat\u00e1logo novedades 2017","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/01\/Disarmodel_2017_redu-292x300.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8242,"url":"https:\/\/blog.ociomodell.com\/wordpress\/clients\/demostraciones-de-paso-a-paso-de-realizacion-de-diversas-tecnicas\/mecha-weathering-washes\/","url_meta":{"origin":8141,"position":5},"title":"Mecha Weathering Washes &#8211; Vallejo","author":"Paco Gomez","date":"26 agosto, 2023","format":false,"excerpt":"Los Mecha Weathering Washes son un producto base agua que tiene muchas aplicaciones para proyectos en Mecha. Se pueden utilizar por si solos o mezclados con colores Vallejo Mecha para obtener un sinf\u00edn de efectos.","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"Los Mecha Weathering washes","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/08\/vallejo-pasoapaso-mecha-weathering-washes-ES.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/P7mZwQ-27j","_links":{"self":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/pages\/8141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8141"}],"version-history":[{"count":0,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/pages\/8141\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}