{"id":7350,"date":"2022-07-04T12:29:31","date_gmt":"2022-07-04T11:29:31","guid":{"rendered":"https:\/\/blog.ociomodell.com\/wordpress\/?p=7350"},"modified":"2024-09-15T18:47:42","modified_gmt":"2024-09-15T16:47:42","slug":"estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350","status":"publish","type":"post","link":"https:\/\/blog.ociomodell.com\/wordpress\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350\/","title":{"rendered":"ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8350."},"content":{"rendered":"<h5><a href=\"https:\/\/ociomodell.com\/ociomodell\/1469-vegetecion-ammo-mig\" rel=\"nofollow noopener\" target=\"_blank\">Ammo of Mig Jimenez<\/a> &#8211; <a href=\"https:\/\/ociomodell.com\/ociomodell\/vegetecion-ammo-mig\/15632-estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-8432074083504.html\" rel=\"nofollow noopener\" target=\"_blank\">ESTEPA PEDREGOSA.<\/a> Dimensiones 230 x 130 mm. Ref: AMI&#8230;&#8230;.<\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7351\" data-permalink=\"https:\/\/blog.ociomodell.com\/wordpress\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350\/\" data-orig-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8350.\" data-image-description=\"&lt;p&gt;ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8350.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8350.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350.jpg\" class=\"size-medium wp-image-7351\" src=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-300x300.jpg\" alt=\"ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8350.\" width=\"300\" height=\"300\" title=\"\" srcset=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-300x300.jpg 300w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-150x150.jpg 150w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-768x768.jpg 768w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-250x250.jpg 250w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-50x50.jpg 50w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2022\/06\/estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/ociomodell.com\/ociomodell\/vegetecion-ammo-mig\/15632-estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-8432074083504.html\" rel=\"nofollow noopener\" target=\"_blank\">&#8211; ESTEPA PEDREGOSA.\u00a0<\/a><\/p>\n<ul>\n<li>\n<p>Dimensiones 230 x 130 mm.<\/p>\n<\/li>\n<li>\n<p>Este producto representa de una manera realista un suelo monta\u00f1oso, incluyendo los matojos, rocas, tierra y colores t\u00edpicos de este paisaje.<\/p>\n<\/li>\n<li>\n<p>Puedes utilizarlo directamente como base para veh\u00edculos o figuras sin necesidad de ser pintado. Tambi\u00e9n se puede recortar f\u00e1cilmente con unas tijeras y adaptarlo a formas de carreteras o caminos para crear grandes escenarios o dioramas.<\/p>\n<\/li>\n<li>\n<p>Se puede pegar f\u00e1cilmente con cola blanca. La forma m\u00e1s efectiva de ambientar nuestros veh\u00edculos o ayudarnos a hacer un diorama.<\/p>\n<\/li>\n<li>\n<p>MARCA: <a href=\"https:\/\/ociomodell.com\/ociomodell\/1469-vegetecion-ammo-mig\" rel=\"nofollow noopener\" target=\"_blank\">AMMO OF MIG JIMENEZ.<\/a><\/p>\n<\/li>\n<li>\n<p><a href=\"https:\/\/ociomodell.com\/ociomodell\/vegetecion-ammo-mig\/15632-estepa-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8350-8432074083504.html\" rel=\"nofollow noopener\" target=\"_blank\">REFERENCIA: AMIG8350<\/a>.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ammo of Mig Jimenez &#8211; ESTEPA PEDREGOSA. Dimensiones 230 x 130 mm. Ref: AMI&#8230;&#8230;. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &#8211; ESTEPA PEDREGOSA.\u00a0 Dimensiones 230 x 130 mm. Este [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[4573,7997],"tags":[794,5080,5081,2745,547,5078,2746,25,2157,140,3937,5079,65,4145],"class_list":["post-7350","post","type-post","status-publish","format-standard","hentry","category-complementos-para-escenografia","category-ammo-mig","tag-794","tag-5080","tag-amig8350","tag-ammo","tag-dimensiones","tag-estepa","tag-jimenez","tag-marca","tag-mig","tag-mm","tag-of","tag-pedregosa","tag-ref","tag-x"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":19170,"url":"https:\/\/blog.ociomodell.com\/wordpress\/suelo-de-montana-pedregosa\/","url_meta":{"origin":7350,"position":0},"title":"SUELO DE MONTA\u00d1A PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8351.","author":"Paco Gomez","date":"28 julio, 2025","format":false,"excerpt":"Descubre el suelo de monta\u00f1a pedregosa de Ammo of Mig Jimenez, ideal para crear escenarios realistas en tus dioramas. Dimensiones 230 x 130 mm. El Suelo de Monta\u00f1a Pedregosa de\u00a0Ammo of Mig Jimenez, con su dise\u00f1o meticuloso y detallado, no solo es un producto altamente funcional, sino que tambi\u00e9n es\u2026","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"SUELO DE MONTA\u00d1A PEDREGOSA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8351","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/07\/suelo-de-montana-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8351.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/07\/suelo-de-montana-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8351.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/07\/suelo-de-montana-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8351.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/07\/suelo-de-montana-pedregosa-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8351.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17416,"url":"https:\/\/blog.ociomodell.com\/wordpress\/estepa-primaveral\/","url_meta":{"origin":7350,"position":1},"title":"ESTEPA PRIMAVERAL. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8353","author":"Paco Gomez","date":"4 mayo, 2025","format":false,"excerpt":"Descubre la Estepa Primaveral de Ammo of Mig Jimenez, un producto ideal para tus dioramas y escenarios. Con dimensiones de 230 x 130 mm, es perfecto para veh\u00edculos y figuras. En resumen, el \"Estepa Primaveral\" de Ammo of Mig Jimenez es un producto imprescindible para cualquier aficionado al modelismo. Con\u2026","rel":"","context":"En \u00abAccesorios escenograf\u00eda\u00bb","block_context":{"text":"Accesorios escenograf\u00eda","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/accesorios-escenografia\/"},"img":{"alt_text":"ESTEPA PRIMAVERAL. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8353","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/05\/estepa-primaveral-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8353.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/05\/estepa-primaveral-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8353.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/05\/estepa-primaveral-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8353.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/05\/estepa-primaveral-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8353.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10803,"url":"https:\/\/blog.ociomodell.com\/wordpress\/terreno-pradera-salvaje\/","url_meta":{"origin":7350,"position":2},"title":"Terreno de Pradera Salvaje. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8361, Incluye matojos, rocas y tierra, replicando fielmente los elementos caracter\u00edsticos de un paisaje de pradera salvaje","author":"Paco Gomez","date":"5 marzo, 2024","format":false,"excerpt":"Descubre el Terreno de Pradera Salvaje de Ammo of Mig Jimenez, con matojos, rocas y tierra, perfecto para recrear paisajes realistas.","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"Terreno de Pradera Salvaje. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8361","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/terreno-de-pradera-salvaje-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83611.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/terreno-de-pradera-salvaje-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83611.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/terreno-de-pradera-salvaje-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83611.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/terreno-de-pradera-salvaje-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83611.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10865,"url":"https:\/\/blog.ociomodell.com\/wordpress\/arbustos-pequenos-otono\/","url_meta":{"origin":7350,"position":3},"title":"Arbustos Peque\u00f1os &#8211; Oto\u00f1o. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8359, representa de una manera realista un suelo monta\u00f1oso, incluyendo los matojos, rocas, tierra y colores t\u00edpicos de este paisaje.","author":"Paco Gomez","date":"9 marzo, 2024","format":false,"excerpt":"Descubre los Arbustos Peque\u00f1os de Oto\u00f1o de Ammo of Mig Jimenez. Representan de manera realista un suelo monta\u00f1oso con matojos, rocas y colores t\u00edpicos. Perfectos para dioramas y escenarios detallados.","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"Arbustos Peque\u00f1os - Oto\u00f1o. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8359","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/arbustos-pequenos-otono-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83591.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/arbustos-pequenos-otono-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83591.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/arbustos-pequenos-otono-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83591.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/03\/arbustos-pequenos-otono-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig83591.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16993,"url":"https:\/\/blog.ociomodell.com\/wordpress\/suelo-de-montana-primavera\/","url_meta":{"origin":7350,"position":4},"title":"SUELO DE MONTA\u00d1A -PRIMAVERA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8358","author":"Paco Gomez","date":"16 abril, 2025","format":false,"excerpt":"Descubre el Suelo de Monta\u00f1a - Primavera de Ammo of Mig Jimenez. Ideal para dioramas y maquetas, con un dise\u00f1o realista y f\u00e1cil de usar. el \"Suelo de Monta\u00f1a - Primavera\" es una adici\u00f3n valiosa para cualquier coleccionista de maquetas, modelistas o aficionados a los dioramas. Su dise\u00f1o realista, facilidad\u2026","rel":"","context":"En \u00abAccesorios escenograf\u00eda\u00bb","block_context":{"text":"Accesorios escenograf\u00eda","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/accesorios-escenografia\/"},"img":{"alt_text":"SUELO DE MONTA\u00d1A -PRIMAVERA. Dimensiones 230 x 130 mm. Marca Ammo of Mig Jimenez. Ref: AMIG8358","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/04\/suelo-de-montana-primavera-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8358.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/04\/suelo-de-montana-primavera-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8358.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/04\/suelo-de-montana-primavera-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8358.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/04\/suelo-de-montana-primavera-dimensiones-230-x-130-mm-marca-ammo-of-mig-jimenez-ref-amig8358.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5090,"url":"https:\/\/blog.ociomodell.com\/wordpress\/ammo-of-mig-jimenez-organizador-pinceles-y-herramientas-ref-amig8028\/","url_meta":{"origin":7350,"position":5},"title":"Ammo of Mig jimenez &#8211; Organizador pinceles y herramientas. Ref: AMIG8028.","author":"Mari Mar Navarro","date":"30 agosto, 2019","format":false,"excerpt":"Ammo of Mig jimenez - Organizador pinceles y herramientas.... Organizador pinceles y herramientas. Marca Ammo of Mig jimenez. Ref: AMIG8028. 9,90 \u20ac impuestos inc. Mas. - ORGANIZADOR PINCELES Y HERRAMIENTAS. - Boomerang es el organizador de pinturas y herramientas m\u00e1s pr\u00e1ctico y c\u00f3modo a la hora de trabajar. Su peque\u00f1o\u2026","rel":"","context":"En \u00abAccesorios - Pintura\u00bb","block_context":{"text":"Accesorios - Pintura","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/ociomodell-accesorios\/accesorios-de-pintura\/"},"img":{"alt_text":"Ammo of Mig jimenez - Organizador pinceles y herramientas. Ref: AMIG8028.","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/08\/8028.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/08\/8028.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/08\/8028.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2019\/08\/8028.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p7mZwQ-1Uy","_links":{"self":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts\/7350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/comments?post=7350"}],"version-history":[{"count":0,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts\/7350\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/media?parent=7350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/categories?post=7350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/tags?post=7350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}