{"id":8717,"date":"2023-10-04T12:13:02","date_gmt":"2023-10-04T10:13:02","guid":{"rendered":"https:\/\/blog.ociomodell.com\/wordpress\/?p=8717"},"modified":"2023-10-04T12:13:02","modified_gmt":"2023-10-04T10:13:02","slug":"helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-02881-riginalmente-disenado-sikorsky-aircraft-armada-estados-unidos-como-helicoptero-guerra-antisubmarina-asw","status":"publish","type":"post","link":"https:\/\/blog.ociomodell.com\/wordpress\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-02881-riginalmente-disenado-sikorsky-aircraft-armada-estados-unidos-como-helicoptero-guerra-antisubmarina-asw\/","title":{"rendered":"Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h1>Helic\u00f3ptero H-34 US MARINES<\/h1>\n<p>El helic\u00f3ptero H-34 US MARINES es un modelo a escala 1:48 de la marca Trumpeter. Este modelo es una r\u00e9plica del helic\u00f3ptero originalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW). Los\u00a0<i>Seabat<\/i>\u00a0desprovistos de equipo antisubmarino y destinados a tareas utilitarias fueron designados\u00a0<b>UH-34G<\/b>\u00a0y\u00a0<b>UH-34J<\/b>. El\u00a0<a title=\"Cuerpo de Marines de los Estados Unidos\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cuerpo_de_Marines_de_los_Estados_Unidos\" rel=\"nofollow noopener\" target=\"_blank\">Cuerpo de Marines de los Estados Unidos<\/a>\u00a0encarg\u00f3 en 1954 la versi\u00f3n\u00a0<b>HUS-1 Seahorse<\/b>\u00a0(<b>UH-34D<\/b>), que transportaba a 12 infantes de marina. Cuatro unidades\u00a0<b>HUS-1L<\/b>\u00a0(<b>LH-34D<\/b>) fueron modificados para realizar operaciones en el \u00c1rtico.<\/p>\n<h2>Caracter\u00edsticas del helic\u00f3ptero H-34 US MARINES<\/h2>\n<ul>\n<li>Kit de montaje en pl\u00e1stico<\/li>\n<li>Contiene 3 decoraciones de calcas y fotograbados<\/li>\n<li>Requiere ensamblado de piezas y pintura<\/li>\n<li>Escala: 1:48<\/li>\n<li>Marca: Trumpeter<\/li>\n<li>Ref: 02881<\/li>\n<\/ul>\n<h2>Descripci\u00f3n del producto<\/h2>\n<p>El helic\u00f3ptero H-34 US MARINES es un modelo a escala 1:48 que ofrece una gran precisi\u00f3n en los detalles. Este kit de montaje en pl\u00e1stico incluye 3 decoraciones de calcas y fotograbados para personalizar el modelo a tu gusto.<\/p>\n<h2>Montaje y pintura<\/h2>\n<p>El ensamblado de las piezas del helic\u00f3ptero H-34 US MARINES requiere de habilidades b\u00e1sicas de modelismo. Sigue las instrucciones proporcionadas en el kit para un montaje correcto. Una vez ensamblado, el modelo puede ser pintado utilizando pinturas acr\u00edlicas o esmaltes para obtener el acabado deseado.<\/p>\n<h2>Enlace de compra<\/h2>\n<p>Puedes adquirir el helic\u00f3ptero H-34 US MARINES a escala 1:48 de la marca Trumpeter en el siguiente enlace: <a href=\"https:\/\/ociomodell.com\/ociomodell\/trumpeter\/12364-helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-02881-9580208028811.html\" rel=\"nofollow noopener\" target=\"_blank\">Comprar ahora<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_8720\" aria-describedby=\"caption-attachment-8720\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8720\" data-permalink=\"https:\/\/blog.ociomodell.com\/wordpress\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-02881-riginalmente-disenado-sikorsky-aircraft-armada-estados-unidos-como-helicoptero-guerra-antisubmarina-asw\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2\/\" data-orig-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"1\" data-image-title=\"Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)\" data-image-description=\"&lt;p&gt;Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1.jpg\" class=\"size-medium wp-image-8720\" src=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-300x300.jpg\" alt=\"Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)\" width=\"300\" height=\"300\" title=\"\" srcset=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-300x300.jpg 300w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-150x150.jpg 150w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-768x768.jpg 768w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-250x250.jpg 250w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1-50x50.jpg 50w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-8720\" class=\"wp-caption-text\">\u00a0 Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)<\/figcaption><\/figure>\n<figure id=\"attachment_8721\" aria-describedby=\"caption-attachment-8721\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8721\" data-permalink=\"https:\/\/blog.ociomodell.com\/wordpress\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-02881-riginalmente-disenado-sikorsky-aircraft-armada-estados-unidos-como-helicoptero-guerra-antisubmarina-asw\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-3\/\" data-orig-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223.jpg\" data-orig-size=\"604,414\" data-comments-opened=\"1\" data-image-title=\"Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)\" data-image-description=\"&lt;p&gt;Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223.jpg\" class=\"size-medium wp-image-8721\" src=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223-300x206.jpg\" alt=\"Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)\" width=\"300\" height=\"206\" title=\"\" srcset=\"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223-300x206.jpg 300w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223-250x171.jpg 250w, https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-2-e1696414362223.jpg 604w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-8721\" class=\"wp-caption-text\">Helic\u00f3ptero H-34 US MARINES. Escala 1:48. Marca Trumpeter. Ref: 02881, riginalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Descubre el helic\u00f3ptero H-34 US MARINES a escala 1:48 de la marca Trumpeter. Un modelo originalmente dise\u00f1ado por Sikorsky Aircraft para la Armada de Estados Unidos como helic\u00f3ptero de guerra antisubmarina (ASW).<\/p>\n","protected":false},"author":2,"featured_media":8719,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[28,5228,464,5730],"tags":[5826,5451,5825,5822,511,2482,5824,244,5823],"class_list":["post-8717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ociomodell","category-articulos","category-ociomodell-escala-148","category-helicoptero","tag-asw","tag-escala-148","tag-guerra-antisubmarina","tag-h-34","tag-helicoptero","tag-modelo","tag-sikorsky-aircraft","tag-trumpeter","tag-us-marines"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/helicoptero-h-34-us-marines-escala-148-marca-trumpeter-ref-028811-e1696414186164.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":14800,"url":"https:\/\/blog.ociomodell.com\/wordpress\/uh-60-mh-60\/","url_meta":{"origin":8717,"position":0},"title":"UH-60 &#8211; MH-60 BLACK HAWK. Escala 1:48. Marca Italeri. Ref: 2706, es uno de los helic\u00f3pteros m\u00e1s ic\u00f3nicos y vers\u00e1tiles de la historia militar, con una amplia trayectoria en misiones de rescate","author":"Paco Gomez","date":"10 diciembre, 2024","format":false,"excerpt":"Descubre el UH-60 - MH-60 Black Hawk en escala 1:48 de la marca Italeri. Un helic\u00f3ptero ic\u00f3nico y vers\u00e1til con una amplia trayectoria en misiones de rescate.","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"UH - 60 \/ MH - 60 BLACK HAWK. Escala 1:48. Marca Italeri. Ref: 2706","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/12\/uh-60-mh-60-black-hawk-escala-148-marca-italeri-ref-2706-e1733865028438.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":17512,"url":"https:\/\/blog.ociomodell.com\/wordpress\/uh-60-mh-60-black-hawk\/","url_meta":{"origin":8717,"position":1},"title":"UH &#8211; 60 \/ MH &#8211; 60 BLACK HAWK. Escala 1:48. Marca Italeri. Ref: 2706","author":"Paco Gomez","date":"8 mayo, 2025","format":false,"excerpt":"Descubre el incre\u00edble modelo UH-60\/MH-60 Black Hawk a escala 1:48 de Italeri. Un kit de montaje que incluye hoja de calcas, ideal para los amantes de la aviaci\u00f3n y el modelismo. El modelo UH-60 \/ MH-60 Black Hawk de Italeri en escala 1:48 no solo es un gran proyecto para\u2026","rel":"","context":"En \u00abModelismo pl\u00e1stico - Helicopteros\u00bb","block_context":{"text":"Modelismo pl\u00e1stico - Helicopteros","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/modelismo-plastico-helicopteros\/"},"img":{"alt_text":"UH - 60 \/ MH - 60 BLACK HAWK. Escala 1:48. Marca Italeri. Ref: 2706","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2025\/05\/uh-60-mh-60-black-hawk-escala-148-marca-italeri-ref-2706-e1746636759734.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8654,"url":"https:\/\/blog.ociomodell.com\/wordpress\/calcas-trenmilitaria-seccion-multitud-calcas-marca-todo-tipo-modelos-helicopteros-cazas-aviones-blindados-carros-combate-etc\/","url_meta":{"origin":8717,"position":2},"title":"CALCAS TRENMILITARIA &#8211; secci\u00f3n con multitud de calcas de la marca para todo tipo de modelos, helic\u00f3pteros, cazas, aviones, blindados, carros de combate, etc","author":"Paco Gomez","date":"2 octubre, 2023","format":false,"excerpt":"CALCAS TRENMILITARIA - secci\u00f3n con multitud de calcas de la marca para todo tipo de modelos, helic\u00f3pteros, cazas, aviones, blindados, carros de combate, etc","rel":"","context":"En \u00abOciomodell\u00bb","block_context":{"text":"Ociomodell","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/ociomodell\/"},"img":{"alt_text":"CALCAS TRENMILITARIA - secci\u00f3n con multitud de calcas de la marca para todo tipo de modelos, helic\u00f3pteros, cazas, aviones, blindados, carros de combate, etc","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/10\/calcas-trenmilitaria-en-tienda.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10215,"url":"https:\/\/blog.ociomodell.com\/wordpress\/chinook-ch-47d-escala-172\/","url_meta":{"origin":8717,"position":3},"title":"\u00abCHINOOK\u00bb CH-47D. Escala 1:72. Marca Trumpeter. Ref: 01622, helic\u00f3ptero bimotor de carga pesada fabricado por la empresa estadounidense Boeing Vertol","author":"Paco Gomez","date":"31 enero, 2024","format":false,"excerpt":"Descubre el helic\u00f3ptero bimotor de carga pesada CHINOOK CH-47D en escala 1:72. Fabricado por la empresa estadounidense Boeing Vertol y marca Trumpeter. Ref: 01622.","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"\" CHINOOK\" CH-47D. Escala 1:72. Marca Trumpeter. Ref: 01622.","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/01\/chinook-ch-47d-escala-172-marca-trumpeter-ref-016221-e1706685508290.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/01\/chinook-ch-47d-escala-172-marca-trumpeter-ref-016221-e1706685508290.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/01\/chinook-ch-47d-escala-172-marca-trumpeter-ref-016221-e1706685508290.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/01\/chinook-ch-47d-escala-172-marca-trumpeter-ref-016221-e1706685508290.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11552,"url":"https:\/\/blog.ociomodell.com\/wordpress\/m198-155mm-medium\/","url_meta":{"origin":8717,"position":4},"title":"M198 155mm Medium Towed Howitzer (early version). Escala 1:35. Marca Trumpeter. Ref: 02306, ha sido utilizado por el Ej\u00e9rcito de EE. UU., el Cuerpo de Marines de EE. UU., as\u00ed como por los ej\u00e9rcitos de India, Tailandia y Australia. Su capacidad de alcance","author":"Paco Gomez","date":"13 mayo, 2024","format":false,"excerpt":"Descubre todo sobre el M198 155mm Medium Towed Howitzer (early version) en escala 1:35 de la marca Trumpeter. Utilizado por varios ej\u00e9rcitos y con una impresionante capacidad de alcance.","rel":"","context":"En \u00abArt\u00edculos\u00bb","block_context":{"text":"Art\u00edculos","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/articulos\/"},"img":{"alt_text":"M198 155mm Medium Towed Howitzer (early version). Escala 1:35. Marca Trumpeter. Ref: 02306","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/05\/m198-155mm-medium-towed-howitzer-early-version-escala-135-marca-trumpeter-ref-023061-e1715611481133.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/05\/m198-155mm-medium-towed-howitzer-early-version-escala-135-marca-trumpeter-ref-023061-e1715611481133.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2024\/05\/m198-155mm-medium-towed-howitzer-early-version-escala-135-marca-trumpeter-ref-023061-e1715611481133.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9029,"url":"https:\/\/blog.ociomodell.com\/wordpress\/uh-60j-rescue-hawk-j-s-d-f-50th-anniversary-escala-172-marca-hasegawa-ref-02384variante-del-black-hawk-utilizado-fuerza-autodefensa-aerea-japon-misiones-busqueda-rescat\/","url_meta":{"origin":8717,"position":5},"title":"UH-60J Rescue Hawk &#8216;J.A.S.D.F. 50th Anniversary&#8217;. Escala 1:72. Marca Hasegawa. Ref: 02384, variante del Black Hawk utilizado por la Fuerza de Autodefensa A\u00e9rea de Jap\u00f3n en misiones de b\u00fasqueda y rescate","author":"Paco Gomez","date":"6 noviembre, 2023","format":false,"excerpt":"Descubre la edici\u00f3n limitada del UH-60J Rescue Hawk","rel":"","context":"En \u00abOciomodell\u00bb","block_context":{"text":"Ociomodell","link":"https:\/\/blog.ociomodell.com\/wordpress\/category\/ociomodell\/"},"img":{"alt_text":"UH-60J Rescue Hawk 'J.A.S.D.F. 50th Anniversary'. Escala 1:72. Marca Hasegawa. Ref: 02384","src":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/11\/uh-60j-rescue-hawk-jasdf-50th-anniversary-escala-172-marca-hasegawa-ref-023841-e1699274674296.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/11\/uh-60j-rescue-hawk-jasdf-50th-anniversary-escala-172-marca-hasegawa-ref-023841-e1699274674296.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blog.ociomodell.com\/wordpress\/wp-content\/uploads\/2023\/11\/uh-60j-rescue-hawk-jasdf-50th-anniversary-escala-172-marca-hasegawa-ref-023841-e1699274674296.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p7mZwQ-2gB","_links":{"self":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts\/8717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8717"}],"version-history":[{"count":0,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/posts\/8717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/media\/8719"}],"wp:attachment":[{"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ociomodell.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}